{"id":1480,"date":"2023-08-22T18:09:42","date_gmt":"2023-08-22T16:09:42","guid":{"rendered":"https:\/\/solergy.ch\/?page_id=1480"},"modified":"2025-07-14T22:57:36","modified_gmt":"2025-07-14T20:57:36","slug":"investition-in-photovoltaikanlagen","status":"publish","type":"page","link":"https:\/\/solergy.ch\/de\/investition-in-photovoltaikanlagen\/","title":{"rendered":"Angebot f\u00fcr Investoren"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1480\" class=\"elementor elementor-1480\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b8f9ab e-con-full sol_banner e-flex e-con e-parent\" data-id=\"2b8f9ab\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7a5d4b elementor-widget elementor-widget-text-editor\" data-id=\"d7a5d4b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>In der ganzen Schweiz nachhaltig in gr\u00fcne Energie investieren<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91d111a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"91d111a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/solergy.ch\/de\/shop\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Anlagem\u00f6glichkeiten ansehen &gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fa088c6 e-flex e-con-boxed e-con e-parent\" data-id=\"fa088c6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3b0f5de e-con-full e-flex e-con e-child\" data-id=\"3b0f5de\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8890a03 elementor-widget elementor-widget-heading\" data-id=\"8890a03\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00f6chten Sie in Solarmodule mit langfristig attraktiven Renditen investieren?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72be578 e-flex e-con-boxed e-con e-child\" data-id=\"72be578\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b541da5 e-flex e-con-boxed e-con e-child\" data-id=\"b541da5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68bf042 elementor-widget elementor-widget-text-editor\" data-id=\"68bf042\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\">Wir bieten Ihnen eine auf Verm\u00f6genswerten basierende, langfristige Impact-Investitionsm\u00f6glichkeit im Bereich erneuerbarer Energien an, die den Anteil gr\u00fcner Verm\u00f6genswerte in Ihrem Portfolio erh\u00f6ht.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74b818c e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"74b818c\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_tablet&quot;:&quot;none&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dbfcca1 e-con-full e-flex e-con e-child\" data-id=\"dbfcca1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eeac818 elementor-widget elementor-widget-text-editor\" data-id=\"eeac818\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Sie k\u00f6nnen in die Errichtung von Solarstromanlagen auf D\u00e4chern investieren, die Solergy von Geb\u00e4udeeigent\u00fcmern mietet.<\/h4><h4>Dank der neuesten Verbesserungen in der Solartechnologie, der allgemeinen Preisentwicklung und der sorgf\u00e4ltig ausgew\u00e4hlten Projekte werden Ihre Solarmodule \u00fcber den gesamten Investitionszeitraum von etwa 20 Jahren eine attraktive Rendite abwerfen.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-710cc6f e-con-full e-flex e-con e-child\" data-id=\"710cc6f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-efed3db elementor-widget elementor-widget-image\" data-id=\"efed3db\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/residential-building-with-solar-panels.jpg\" class=\"attachment-large size-large wp-image-1980\" alt=\"\" srcset=\"https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/residential-building-with-solar-panels.jpg 800w, https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/residential-building-with-solar-panels-600x400.jpg 600w, https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/residential-building-with-solar-panels-300x200.jpg 300w, https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/residential-building-with-solar-panels-768x512.jpg 768w, https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/residential-building-with-solar-panels-18x12.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1561edd e-flex e-con-boxed e-con e-parent\" data-id=\"1561edd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9cb6550 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"9cb6550\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_tablet&quot;:&quot;none&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b154013 e-con-full e-flex e-con e-child\" data-id=\"b154013\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b258149 elementor-widget elementor-widget-image\" data-id=\"b258149\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"533\" data-src=\"https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/Man-in-suit-calculating-ROI-on-solar-investment-1.jpg\" class=\"attachment-large size-large wp-image-1979 lazyload\" alt=\"\" data-srcset=\"https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/Man-in-suit-calculating-ROI-on-solar-investment-1.jpg 800w, https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/Man-in-suit-calculating-ROI-on-solar-investment-1-600x400.jpg 600w, https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/Man-in-suit-calculating-ROI-on-solar-investment-1-300x200.jpg 300w, https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/Man-in-suit-calculating-ROI-on-solar-investment-1-768x512.jpg 768w, https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/Man-in-suit-calculating-ROI-on-solar-investment-1-18x12.jpg 18w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/533;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65e0a62 e-con-full e-flex e-con e-child\" data-id=\"65e0a62\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4fab556 elementor-widget elementor-widget-text-editor\" data-id=\"4fab556\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Bereits ab dem ersten Tag der Inbetriebnahme der Solaranlage, kann mit dem produzierten Strom Geld verdient werden.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb968e3 e-flex e-con-boxed e-con e-parent\" data-id=\"bb968e3\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-30b5f05 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"30b5f05\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_tablet&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-914f4c3 e-con-full featured_block e-flex e-con e-child\" data-id=\"914f4c3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-648ecb8 elementor-widget elementor-widget-heading\" data-id=\"648ecb8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Ausgew\u00e4hlte Projekte<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a58253 elementor-widget elementor-widget-text-editor\" data-id=\"6a58253\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Erwerben Sie Anteile an Solaranlagen auf Schweizer D\u00e4chern. Profitieren Sie vom Verkauf von Strom und tragen Sie zum Schutz der Umwelt bei.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ef9632 elementor-widget elementor-widget-shortcode\" data-id=\"9ef9632\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class='Main_wrapper swiffy-slider slider-item-show1  slider-item-show2-sm slider-nav-round slider-nav-sm slider-nav-visible slider-item-first-visible slider-nav-autopause slider-indicators-round slider-indicators-dark slider-indicators-outside slider-indicators-sm  woo_slider1'>  <ul class='slider-container'><li class='slider_card slide-visible'> <div class='post_card'><a href=\"https:\/\/solergy.ch\/de\/produkt\/11-apartment-condo-building-muhen\/\" style=\"position: relative;\"><img decoding=\"async\" width=\"1000\" height=\"776\" data-src=\"https:\/\/solergy.ch\/wp-content\/uploads\/2026\/01\/Muhen2-1.webp\" class=\"attachment-shop_single size-shop_single wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/solergy.ch\/wp-content\/uploads\/2026\/01\/Muhen2-1.webp 1000w, https:\/\/solergy.ch\/wp-content\/uploads\/2026\/01\/Muhen2-1-300x233.webp 300w, https:\/\/solergy.ch\/wp-content\/uploads\/2026\/01\/Muhen2-1-768x596.webp 768w, https:\/\/solergy.ch\/wp-content\/uploads\/2026\/01\/Muhen2-1-15x12.webp 15w, https:\/\/solergy.ch\/wp-content\/uploads\/2026\/01\/Muhen2-1-600x466.webp 600w\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1000px; --smush-placeholder-aspect-ratio: 1000\/776;\" \/><\/a><span class='wwo_card_details'><a class=\"p_title\" href=\"https:\/\/solergy.ch\/de\/produkt\/11-apartment-condo-building-muhen\/\">Muhen, AG<\/a>Solarsystem auf dem Dach eines Geb\u00e4udes mit 11 Wohnungen.<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;750<\/bdi><\/span> <small class=\"woocommerce-price-suffix\">(inkl. MwSt.)<\/small><\/span><div><a href=\"https:\/\/solergy.ch\/de\/produkt\/11-apartment-condo-building-muhen\/\" class=\"featured-btn sol-button mid-button\">Details ansehen &gt;&gt;<\/a><\/div><\/span'><\/div><\/li><li class='slider_card slide-visible'> <div class='post_card'><a href=\"https:\/\/solergy.ch\/de\/produkt\/solarpanels-in-muhen\/\" style=\"position: relative;\"><img decoding=\"async\" width=\"1001\" height=\"766\" data-src=\"https:\/\/solergy.ch\/wp-content\/uploads\/2024\/11\/muhen-aerial-1.webp\" class=\"attachment-shop_single size-shop_single wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/solergy.ch\/wp-content\/uploads\/2024\/11\/muhen-aerial-1.webp 1001w, https:\/\/solergy.ch\/wp-content\/uploads\/2024\/11\/muhen-aerial-1-600x459.webp 600w, https:\/\/solergy.ch\/wp-content\/uploads\/2024\/11\/muhen-aerial-1-300x230.webp 300w, https:\/\/solergy.ch\/wp-content\/uploads\/2024\/11\/muhen-aerial-1-768x588.webp 768w, https:\/\/solergy.ch\/wp-content\/uploads\/2024\/11\/muhen-aerial-1-16x12.webp 16w\" data-sizes=\"(max-width: 1001px) 100vw, 1001px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1001px; --smush-placeholder-aspect-ratio: 1001\/766;\" \/><\/a><span class='wwo_card_details'><a class=\"p_title\" href=\"https:\/\/solergy.ch\/de\/produkt\/solarpanels-in-muhen\/\">Muhen, AG<\/a>Solaranlage auf dem Dach eines Geb\u00e4udes mit 8 Wohnungen.<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;1'125<\/bdi><\/span> <small class=\"woocommerce-price-suffix\">(inkl. MwSt.)<\/small><\/span><div><a href=\"https:\/\/solergy.ch\/de\/produkt\/solarpanels-in-muhen\/\" class=\"featured-btn sol-button mid-button\">Details ansehen &gt;&gt;<\/a><\/div><\/span'><\/div><\/li><li class='slider_card slide-visible'> <div class='post_card'><a href=\"https:\/\/solergy.ch\/de\/produkt\/solarpanel-auf-einem-reiterhof-in-tatroz-fr\/\" style=\"position: relative;\"><img decoding=\"async\" width=\"1151\" height=\"750\" data-src=\"https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Tatroz-6.webp\" class=\"attachment-shop_single size-shop_single wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Tatroz-6.webp 1151w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Tatroz-6-600x391.webp 600w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Tatroz-6-300x195.webp 300w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Tatroz-6-1024x667.webp 1024w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Tatroz-6-768x500.webp 768w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Tatroz-6-18x12.webp 18w\" data-sizes=\"(max-width: 1151px) 100vw, 1151px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1151px; --smush-placeholder-aspect-ratio: 1151\/750;\" \/><\/a><span class='wwo_card_details'><a class=\"p_title\" href=\"https:\/\/solergy.ch\/de\/produkt\/solarpanel-auf-einem-reiterhof-in-tatroz-fr\/\">Tatroz, FR<\/a>Solaranlage auf dem Dach eines Bauernhauses in Tatroz<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;510<\/bdi><\/span> <small class=\"woocommerce-price-suffix\">(inkl. MwSt.)<\/small><\/span><div><a href=\"https:\/\/solergy.ch\/de\/produkt\/solarpanel-auf-einem-reiterhof-in-tatroz-fr\/\" class=\"featured-btn sol-button mid-button\">Details ansehen &gt;&gt;<\/a><\/div><\/span'><\/div><\/li><li class='slider_card slide-visible'> <div class='post_card'><a href=\"https:\/\/solergy.ch\/de\/produkt\/solarmodul-auf-einem-lagerhaus-in-missy-vd\/\" style=\"position: relative;\"><img decoding=\"async\" width=\"1151\" height=\"750\" data-src=\"https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Missy-1-1.webp\" class=\"attachment-shop_single size-shop_single wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Missy-1-1.webp 1151w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Missy-1-1-600x391.webp 600w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Missy-1-1-300x195.webp 300w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Missy-1-1-1024x667.webp 1024w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Missy-1-1-768x500.webp 768w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Missy-1-1-18x12.webp 18w\" data-sizes=\"(max-width: 1151px) 100vw, 1151px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1151px; --smush-placeholder-aspect-ratio: 1151\/750;\" \/><\/a><span class='wwo_card_details'><a class=\"p_title\" href=\"https:\/\/solergy.ch\/de\/produkt\/solarmodul-auf-einem-lagerhaus-in-missy-vd\/\">Missy, VD<\/a>Solaranlage auf dem Dach eines Lagerhauses in Missy<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;505<\/bdi><\/span> <small class=\"woocommerce-price-suffix\">(inkl. MwSt.)<\/small><\/span><div><a href=\"https:\/\/solergy.ch\/de\/produkt\/solarmodul-auf-einem-lagerhaus-in-missy-vd\/\" class=\"featured-btn sol-button mid-button\">Details ansehen &gt;&gt;<\/a><\/div><\/span'><\/div><\/li><li class='slider_card slide-visible'> <div class='post_card'><a href=\"https:\/\/solergy.ch\/de\/produkt\/solarpanel-auf-einer-geflugelfarm-in-le-cret-fr\/\" style=\"position: relative;\"><img decoding=\"async\" width=\"1003\" height=\"766\" data-src=\"https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Le-Cret_1.webp\" class=\"attachment-shop_single size-shop_single wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Le-Cret_1.webp 1003w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Le-Cret_1-600x458.webp 600w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Le-Cret_1-300x229.webp 300w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Le-Cret_1-768x587.webp 768w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Le-Cret_1-16x12.webp 16w\" data-sizes=\"(max-width: 1003px) 100vw, 1003px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1003px; --smush-placeholder-aspect-ratio: 1003\/766;\" \/><\/a><span class='wwo_card_details'><a class=\"p_title\" href=\"https:\/\/solergy.ch\/de\/produkt\/solarpanel-auf-einer-geflugelfarm-in-le-cret-fr\/\">Le Cr\u00eat, FR<\/a>Solaranlage auf dem Dach eines Bauernhauses in Le Cr\u00eat<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;400<\/bdi><\/span> <small class=\"woocommerce-price-suffix\">(inkl. MwSt.)<\/small><\/span><div><a href=\"https:\/\/solergy.ch\/de\/produkt\/solarpanel-auf-einer-geflugelfarm-in-le-cret-fr\/\" class=\"featured-btn sol-button mid-button\">Details ansehen &gt;&gt;<\/a><\/div><\/span'><\/div><\/li><li class='slider_card slide-visible'> <div class='post_card'><a href=\"https:\/\/solergy.ch\/de\/produkt\/solarpanels-in-menziken\/\" style=\"position: relative;\"><img decoding=\"async\" width=\"1000\" height=\"766\" data-src=\"https:\/\/solergy.ch\/wp-content\/uploads\/2022\/03\/Menziken-1.webp\" class=\"attachment-shop_single size-shop_single wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/solergy.ch\/wp-content\/uploads\/2022\/03\/Menziken-1.webp 1000w, https:\/\/solergy.ch\/wp-content\/uploads\/2022\/03\/Menziken-1-600x460.webp 600w, https:\/\/solergy.ch\/wp-content\/uploads\/2022\/03\/Menziken-1-300x230.webp 300w, https:\/\/solergy.ch\/wp-content\/uploads\/2022\/03\/Menziken-1-768x588.webp 768w, https:\/\/solergy.ch\/wp-content\/uploads\/2022\/03\/Menziken-1-16x12.webp 16w\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1000px; --smush-placeholder-aspect-ratio: 1000\/766;\" \/><\/a><span class='wwo_card_details'><a class=\"p_title\" href=\"https:\/\/solergy.ch\/de\/produkt\/solarpanels-in-menziken\/\">Menziken, AG<\/a>Solaranlage auf dem Dach eines Wohnhauses mit 9 Wohnungen.<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;1'231<\/bdi><\/span> <small class=\"woocommerce-price-suffix\">(inkl. MwSt.)<\/small><\/span><div><a href=\"https:\/\/solergy.ch\/de\/produkt\/solarpanels-in-menziken\/\" class=\"featured-btn sol-button mid-button\">Details ansehen &gt;&gt;<\/a><\/div><\/span'><\/div><\/li><li class='slider_card slide-visible'> <div class='post_card'><a href=\"https:\/\/solergy.ch\/de\/produkt\/solar-panel-on-two-farm-buildings-in-bassecourt-canton-jura\/\" style=\"position: relative;\"><img decoding=\"async\" width=\"1000\" height=\"766\" data-src=\"https:\/\/solergy.ch\/wp-content\/uploads\/2025\/10\/Bascourt-aerial-3-new.webp\" class=\"attachment-shop_single size-shop_single wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/solergy.ch\/wp-content\/uploads\/2025\/10\/Bascourt-aerial-3-new.webp 1000w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/10\/Bascourt-aerial-3-new-300x230.webp 300w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/10\/Bascourt-aerial-3-new-768x588.webp 768w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/10\/Bascourt-aerial-3-new-16x12.webp 16w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/10\/Bascourt-aerial-3-new-600x460.webp 600w\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1000px; --smush-placeholder-aspect-ratio: 1000\/766;\" \/><\/a><span class='wwo_card_details'><a class=\"p_title\" href=\"https:\/\/solergy.ch\/de\/produkt\/solar-panel-on-two-farm-buildings-in-bassecourt-canton-jura\/\">Bassecourt, JU<\/a>Solaranlage auf dem Dach eines Bauernhauses in Bassecourt<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;625<\/bdi><\/span> <small class=\"woocommerce-price-suffix\">(inkl. MwSt.)<\/small><\/span><div><a href=\"https:\/\/solergy.ch\/de\/produkt\/solar-panel-on-two-farm-buildings-in-bassecourt-canton-jura\/\" class=\"featured-btn sol-button mid-button\">Details ansehen &gt;&gt;<\/a><\/div><\/span'><\/div><\/li><li class='slider_card slide-visible'> <div class='post_card'><a href=\"https:\/\/solergy.ch\/de\/produkt\/solarmodul-auf-einem-sagewerk-in-vicques-ju\/\" style=\"position: relative;\"><img decoding=\"async\" width=\"1000\" height=\"563\" data-src=\"https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Vicques_aerial_original.webp\" class=\"attachment-shop_single size-shop_single wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Vicques_aerial_original.webp 1000w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Vicques_aerial_original-600x338.webp 600w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Vicques_aerial_original-300x169.webp 300w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Vicques_aerial_original-768x432.webp 768w, https:\/\/solergy.ch\/wp-content\/uploads\/2025\/04\/Vicques_aerial_original-18x10.webp 18w\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1000px; --smush-placeholder-aspect-ratio: 1000\/563;\" \/><\/a><span class='wwo_card_details'><a class=\"p_title\" href=\"https:\/\/solergy.ch\/de\/produkt\/solarmodul-auf-einem-sagewerk-in-vicques-ju\/\">Vicques, JU<\/a>Solaranlage auf dem Dach eines Bauernhauses in Vicques<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;550<\/bdi><\/span> <small class=\"woocommerce-price-suffix\">(inkl. MwSt.)<\/small><\/span><div><a href=\"https:\/\/solergy.ch\/de\/produkt\/solarmodul-auf-einem-sagewerk-in-vicques-ju\/\" class=\"featured-btn sol-button mid-button\">Details ansehen &gt;&gt;<\/a><\/div><\/span'><\/div><\/li><\/ul>\n\t\t\t<button type=\"button\" class=\"slider-nav\" aria-label=\"Nach links gehen\"><\/button>\n\t\t<button type=\"button\" class=\"slider-nav slider-nav-next\" aria-label=\"Nach links gehen\"><\/button>\n\n\t\t\n\t<div class=\"slider-indicators\">\n        <button class=\"active\" aria-label=\"Zum Dia gehen\"><\/button>\n     \n        <button aria-label=\"Zum Dia gehen\"><\/button>\n     \n        <button aria-label=\"Zum Dia gehen\"><\/button>\n     \n        <button aria-label=\"Zum Dia gehen\"><\/button>\n     \n        <button aria-label=\"Zum Dia gehen\"><\/button>\n     \n    <\/div>\n     <\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b547988 elementor-widget elementor-widget-text-editor\" data-id=\"b547988\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Sind Sie ein Geb\u00e4udeeigent\u00fcmer? Erfahren Sie, wie die Eigent\u00fcmer und Mieter dieser Geb\u00e4ude von unserer L\u00f6sung profitieren und kontaktieren Sie uns, um eine Beurteilung Ihres Geb\u00e4udes zu erhalten.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-904b2fb e-con-full e-flex e-con e-parent\" data-id=\"904b2fb\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-207fe04 e-con-full e-flex e-con e-child\" data-id=\"207fe04\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5deb5bd elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5deb5bd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/solergy.ch\/de\/shop\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Anlagem\u00f6glichkeiten ansehen &gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-991fd26 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"991fd26\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-873168d\" data-id=\"873168d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2191ac elementor-widget elementor-widget-menu-anchor\" data-id=\"f2191ac\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"invest-faq\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67703cf elementor-widget elementor-widget-heading\" data-id=\"67703cf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ - H\u00e4ufige Fragen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47aa674 elementor-widget elementor-widget-toggle\" data-id=\"47aa674\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7511\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-7511\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Warum sind die Panelpreise so hoch?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7511\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-7511\"><p>In unserem Modell stellt jedes Solarpanel einen Miteigentumsanteil an einer Solaranlage dar. Der Preis deckt die anteiligen Kosten f\u00fcr die Panels, den Wechselrichter, die Verkabelung, die Batterien, die Installation und alles andere, was f\u00fcr den Betrieb der Solaranlage ben\u00f6tigt wird, damit sie Strom produzieren kann, aus dessen Verkauf wir die Panelbesitzer \u00fcber 30 Jahre hinweg verg\u00fcten. Das erkl\u00e4rt auch, warum der Preis f\u00fcr die Panels bei jedem Projekt anders ist.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7512\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-7512\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Bis wann muss ich entscheiden, ob ich Solarpaneele in einem Projekt kaufen m\u00f6chte?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7512\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-7512\"><p>Der erste Schritt ist eine Dachnutzungsvertrag. Darauf folgt unsere genaue Projektplanung, einschliesslich der Definition der Kapazit\u00e4t und des Finanzierungsbedarfs. Anschliessend kontaktieren wir die Eigent\u00fcmer mit konkreten Investitionsm\u00f6glichkeiten und schliesslich die externen Investoren. Die Investitionszahlen in unserem Vorschlag basieren auf Sch\u00e4tzungen nach bestem Wissen; kleine Anpassungen k\u00f6nnen sich durch die detaillierte Projektplanung ergeben.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7513\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-7513\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ben\u00f6tigt Solergy eine Investition von den Immobilieneigent\u00fcmern, um die Solaranlage zu finanzieren?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7513\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-7513\"><p>Die Eigent\u00fcmer haben einzigartige M\u00f6glichkeiten, von einer Solaranlage auf ihrem Dach zu profitieren, insbesondere Eigent\u00fcmer, die auch im Geb\u00e4ude wohnen (Steuervorteile, g\u00fcnstigerer Strom). Diese Optionen stehen externen Investoren nicht zur Verf\u00fcgung. Deshalb bieten wir den Eigent\u00fcmern vorrangig die M\u00f6glichkeit zu investieren. Sobald alle Eigent\u00fcmer auf unseren Investitionsaufruf reagiert haben, \u00f6ffnen wir das Projekt f\u00fcr externe private oder institutionelle Investoren.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7514\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-7514\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Sind die Leistungszahlen des Projekts endg\u00fcltig?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7514\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-7514\"><p>Die Zahlen sind ungef\u00e4hre Werte, die auf \u00f6ffentlich verf\u00fcgbaren Informationen \u00fcber das Solarpotenzial des Daches basieren. Sobald eine Dachnutzungsvertrag besteht, werden wir das Dach und den Stromverbrauch im Geb\u00e4ude untersuchen und die Zahlen finalisieren.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7515\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-7515\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Gibt es staatliche oder kantonale F\u00f6rderungen f\u00fcr die Solaranlage?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7515\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-7515\"><p>Ja, es gibt eine staatliche F\u00f6rderung f\u00fcr Solaranlagen. Diese kann auf der Website pronovo.ch eingesehen werden. Der Subventionsbetrag ist bereits im berechneten Preis der Solarmodule enthalten und wird von Solergy vorfinanziert und somit vom Staat bezogen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7516\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-7516\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Was passiert, wenn ich meinen Anteil in Form von Solarpaneelen bereits gekauft habe und das Projekt nicht realisiert wird?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7516\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-7516\"><p>Solergy erteilt den Subunternehmern den Auftrag zur Umsetzung erst, wenn 100 % der Finanzierung gesichert ist. Sollte dies innerhalb des im Dachnutzungsvertrag vorgesehenen Zeitraums nicht gelingen, sagen wir das Projekt ab und erstatten den Investoren die Kaufbetr\u00e4ge zur\u00fcck oder, falls sie es w\u00fcnschen, k\u00f6nnen ihre Betr\u00e4ge auf andere Projekte umverteilt werden.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7517\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-7517\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Was passiert, falls Solergy insolvent wird?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7517\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-7517\"><p>Die beste Rentabilit\u00e4t wird erreicht, wenn die Anlage \u00fcber ihren gesamten Lebenszyklus an ihrem urspr\u00fcnglichen Standort bleibt. Im unwahrscheinlichen Fall, dass Solergy vor Ablauf der Vertragslaufzeit verschwindet, besteht das Interesse eines m\u00f6glichen neuen Betreibers darin, die Anlage weiterhin auf dem urspr\u00fcnglichen Dach zu betreiben, da der Abbau der Module und deren Verlagerung auf ein anderes Dach fast so teuer ist wie der Bau einer neuen Anlage. Es gibt zwei Szenarien:<br \/>a) Ein Nachfolger von Solergy (ein anderer Auftragnehmer oder Stromanbieter) setzt den Betrieb der Anlage fort, verkauft den Strom und zahlt gem\u00e4ss dem urspr\u00fcnglichen Vertrag und den geltenden Gesetzen die Ertr\u00e4ge an die Investoren und den Dachbesitzer.<br \/>b) Der Dachbesitzer kauft die PV-Anlage und entsch\u00e4digt die Investoren mit dem Restwert der Module.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7518\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-7518\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Kann ich die Solarpaneele, die ich besitze, aber Teil einer Solaranlage sind, verkaufen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7518\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-7518\"><p>Ja. Ihre Investition ist der Besitz von Solarmodulen in einer Solaranlage. Sie k\u00f6nnen diesen Anteil verkaufen, und er kann auch vererbt werden. Damit Solergy die Ertr\u00e4ge an den neuen Eigent\u00fcmer auszahlen kann, teilen Sie uns bitte dessen Kontaktdaten und Kontonummer mit.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-11b992f e-flex e-con-boxed e-con e-parent\" data-id=\"11b992f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b968af6 e-flex e-con-boxed e-con e-child\" data-id=\"b968af6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ef3792 elementor-widget elementor-widget-heading\" data-id=\"8ef3792\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sie sind Eigent\u00fcmer oder Miteigent\u00fcmer einer Immobilie, aber nicht bereit, die Gesamtkosten f\u00fcr eine Solaranlage zu tragen?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4f3612 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"a4f3612\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_tablet&quot;:&quot;none&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d78507f e-con-full e-flex e-con e-child\" data-id=\"d78507f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9e50d3 elementor-widget elementor-widget-image\" data-id=\"e9e50d3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" data-src=\"https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/Industrial-property-with-solar-panels.jpg\" class=\"attachment-large size-large wp-image-1351 lazyload\" alt=\"\" data-srcset=\"https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/Industrial-property-with-solar-panels.jpg 800w, https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/Industrial-property-with-solar-panels-400x300.jpg 400w, https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/Industrial-property-with-solar-panels-600x450.jpg 600w, https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/Industrial-property-with-solar-panels-300x225.jpg 300w, https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/Industrial-property-with-solar-panels-768x576.jpg 768w, https:\/\/solergy.ch\/wp-content\/uploads\/2023\/08\/Industrial-property-with-solar-panels-16x12.jpg 16w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/600;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d8319dc e-con-full e-flex e-con e-child\" data-id=\"d8319dc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7127e88 elementor-widget elementor-widget-text-editor\" data-id=\"7127e88\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Profitieren Sie von unserem Mietmodell f\u00fcr D\u00e4cher, das f\u00fcr Immobilienbesitzer entwickelt wurde. <\/strong><\/h3><h3><strong>Neben einer Dachmiete und der Bezugsm\u00f6glichkeit von gr\u00fcnem Strom, k\u00f6nnen Sie auch in die Solaranlage investieren.<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9f542e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d9f542e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/solergy.ch\/de\/kostenlose-photovoltaikanlage-fur-eigentumer\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr \u00fcber unsere L\u00f6sung f\u00fcr Immobilienbesitzer &gt;&gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da17407 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da17407\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7683ec9\" data-id=\"7683ec9\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19c6f76 elementor-widget elementor-widget-menu-anchor\" data-id=\"19c6f76\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"contact_us_investor\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dce88e elementor-widget elementor-widget-heading\" data-id=\"1dce88e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kontaktieren Sie uns f\u00fcr weitere Investitionsm\u00f6glichkeiten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-627a26c elementor-widget elementor-widget-shortcode\" data-id=\"627a26c\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"wpforms-container solergy_contact\" id=\"wpforms-797\"><form id=\"wpforms-form-797\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"797\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/de\/wp-json\/wp\/v2\/pages\/1480\" data-token=\"afe27ec211f84adcda0d32d43ff4b1ad\" data-token-time=\"1784158047\" data-trp-original-action=\"\/de\/wp-json\/wp\/v2\/pages\/1480\"><noscript class=\"wpforms-error-noscript\">Bitte aktivieren Sie JavaScript in Ihrem Browser, um dieses Formular fertigzustellen.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-797-field_8-container\" class=\"wpforms-field wpforms-field-select wpforms-one-third wpforms-first wpforms-field-select-style-classic\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-797-field_8\">Anrede <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-797-field_8\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][8]\" required=\"required\"><option value=\"Mr.\"  class=\"choice-1 depth-1\"  >Herr<\/option><option value=\"Ms.\"  class=\"choice-2 depth-1\"  >Frau<\/option><\/select><\/div><div id=\"wpforms-797-field_5-container\" class=\"wpforms-field wpforms-field-name wpforms-one-third\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-797-field_5\">Vorname <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-797-field_5\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-797-field_9-container\" class=\"wpforms-field wpforms-field-name wpforms-one-third\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-797-field_9\">Nachname <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-797-field_9\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][9]\" required><\/div><div id=\"wpforms-797-field_6-container\" class=\"wpforms-field wpforms-field-email wpforms-one-half wpforms-first\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-797-field_6\">E-Mail <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-797-field_6\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][6]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-797-field_10-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-797-field_10\">Telefon <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-797-field_10\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][10]\" required><\/div><div id=\"wpforms-797-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-797-field_2\">Bemerkung <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-797-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><div id=\"wpforms-797-field_3-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"3\"><label class=\"wpforms-field-label\">GDPR Vereinbarung <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-797-field_3\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-797-field_3_1\" name=\"wpforms[fields][3][]\" value=\"I consent to having this website store my submitted information so they can respond to my inquiry.\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-797-field_3_1\">Hiermit stimme ich zu, dass diese Website meine eingereichten Informationen speichert, um auf die Anfrage reagieren zu k\u00f6nnen.<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-invisible\" ><div class=\"g-recaptcha\" data-sitekey=\"6Ldx_W0gAAAAAC_MstFjeO08fSKNz7opCUNEQeK6\" data-size=\"invisible\"><\/div><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"797\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/solergy.ch\/de\/wp-json\/wp\/v2\/pages\/1480\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-797\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Send\" aria-live=\"assertive\" value=\"wpforms-submit\">Senden<\/button><img decoding=\"async\" data-src=\"https:\/\/solergy.ch\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner lazyload\" style=\"--smush-placeholder-width: 26px; --smush-placeholder-aspect-ratio: 26\/26;display: none;\" width=\"26\" height=\"26\" alt=\"Wird geladen\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form><\/div>  <!-- .wpforms-container --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nachhaltig in gr\u00fcne Energie investieren, \u00fcberall in der Schweiz Anlagem\u00f6glichkeiten ansehen &gt;&gt; Sie m\u00f6chten in Solarpaneele mit langfristig attraktiven Renditen investieren? Wir bieten Ihnen eine anlagenbasierte, langfristig wirksame Investitionsm\u00f6glichkeit in erneuerbare Energien, die den Anteil gr\u00fcner Anlagen in Ihrem Portfolio erh\u00f6ht. Sie k\u00f6nnen in die Errichtung von Solarstromanlagen investieren [...]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1480","page","type-page","status-publish","hentry","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-product-gallery-with-no-image","ast-product-tabs-layout-horizontal","ast-qv-on-image"],"_links":{"self":[{"href":"https:\/\/solergy.ch\/de\/wp-json\/wp\/v2\/pages\/1480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solergy.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solergy.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solergy.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solergy.ch\/de\/wp-json\/wp\/v2\/comments?post=1480"}],"version-history":[{"count":264,"href":"https:\/\/solergy.ch\/de\/wp-json\/wp\/v2\/pages\/1480\/revisions"}],"predecessor-version":[{"id":3733,"href":"https:\/\/solergy.ch\/de\/wp-json\/wp\/v2\/pages\/1480\/revisions\/3733"}],"wp:attachment":[{"href":"https:\/\/solergy.ch\/de\/wp-json\/wp\/v2\/media?parent=1480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}